{"id":6576,"date":"2015-09-21T15:00:43","date_gmt":"2015-09-21T15:00:43","guid":{"rendered":"http:\/\/www.federacaopaulistadefutsal.com.br\/?p=6576"},"modified":"2015-09-21T15:00:43","modified_gmt":"2015-09-21T15:00:43","slug":"apos-vitoria-contra-pulo-do-gato-taubate-perde-a-primeira-na-copa-paulista","status":"publish","type":"post","link":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/apos-vitoria-contra-pulo-do-gato-taubate-perde-a-primeira-na-copa-paulista\/","title":{"rendered":"Ap\u00f3s vit\u00f3ria contra Pulo do Gato, Taubat\u00e9 perde a primeira na Copa Paulista"},"content":{"rendered":"<p>&nbsp;<br \/>\nO\u00a0Taubat\u00e9 enfrentou a A.A.B.B., nesse s\u00e1bado (19), pela segunda rodada da Copa Paulista e foi derrotada por 3 a 2 na casa do advers\u00e1rio. Foi o primeiro rev\u00e9s da equipe na competi\u00e7\u00e3o ap\u00f3s vit\u00f3ria sobre o Pulo do Gato na estreia.<br \/>\nNo primeiro tempo, os visitantes balan\u00e7aram as redes duas vezes. O Taubat\u00e9\u00a0diminuiu com Hernandes, por\u00e9m os anfitri\u00f5es ampliaram novamente. Na etapa complementar, os taubateanos foram mais ofensivos, marcaram o segundo com Hernandes novamente e, por pouco, n\u00e3o empataram.<br \/>\n<strong>\u201cInfelizmente a gente esperava somar pontos fora de casa. Cometemos alguns erros individuais e coletivos que prejudicaram nosso desempenho. Apesar da derrota, j\u00e1 temos que pensar no pr\u00f3ximo jogo e buscar os tr\u00eas pontos\u201d,<\/strong> disse Bruno Zuchinalli, t\u00e9cnico do Taubat\u00e9.<br \/>\nA terceira partida no Estadual ser\u00e1 na sexta-feira (25), contra o Indaiatuba, \u00e0s 20h45, no gin\u00e1sio do Cemte, em Taubat\u00e9-SP.<br \/>\n&nbsp;<br \/>\nPor Assessoria FPFS<br \/>\nCom informa\u00e7\u00f5es: Top 10 Comunica\u00e7\u00e3o<br \/>\nFoto: Divulga\u00e7\u00e3o\/ Jonas Barbetta\/\u00a0Top 10 Comunica\u00e7\u00e3o<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; O\u00a0Taubat\u00e9 enfrentou a A.A.B.B., nesse s\u00e1bado (19), pela segunda rodada da Copa Paulista e foi derrotada por 3 a<\/p>\n","protected":false},"author":1,"featured_media":6577,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,32],"tags":[134,718,888,1334,1556,2414,2419],"class_list":["post-6576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copa-paulista","category-maiores","tag-aabb","tag-copa-paulista","tag-duelo","tag-interior","tag-lpf","tag-taubate","tag-taubateanos"],"_links":{"self":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts\/6576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/comments?post=6576"}],"version-history":[{"count":0,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts\/6576\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/media?parent=6576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/categories?post=6576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/tags?post=6576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}