{"id":9150,"date":"2016-02-25T14:00:20","date_gmt":"2016-02-25T14:00:20","guid":{"rendered":"http:\/\/www.federacaopaulistadefutsal.com.br\/?p=9150"},"modified":"2016-02-25T14:00:20","modified_gmt":"2016-02-25T14:00:20","slug":"goleiro-do-jacarei-bruno-donha-fala-sobre-primeiros-dias-de-pre-temporada","status":"publish","type":"post","link":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/goleiro-do-jacarei-bruno-donha-fala-sobre-primeiros-dias-de-pre-temporada\/","title":{"rendered":"Goleiro do Jacare\u00ed, Bruno Donha fala sobre primeiros dias de pr\u00e9-temporada"},"content":{"rendered":"<p>&nbsp;<br \/>\nNa \u00faltima semana, o Jacare\u00ed Futsal, time do interior paulista, iniciou oficialmente sua\u00a0pr\u00e9-temporada. Goleiro da equipe jacareiense, Bruno Donha falou sobre os primeiros dias de trabalho nas quatro linhas da quadra. Confira!<br \/>\n<strong>&#8220;J\u00e1 fizemos os exames m\u00e9dicos e agora estamos realizando trabalhos na academia, na quadra e tamb\u00e9m na pista. \u00c9 uma prepara\u00e7\u00e3o bem forte e mesmo assim j\u00e1 estou me sentindo muito bem fisicamente&#8221;,\u00a0<\/strong>revelou o jogador das traves.\u00a0<strong>&#8220;Foi montado um elenco que vem para brigar nos jogos de igual pra igual e isso nos d\u00e1 muita confian\u00e7a. Fora dos treinos s\u00e3o todos &#8216;gente boa&#8217;\u00a0e n\u00e3o tem nem o que falar. Todos os anos o elenco do Jacare\u00ed tem bastante companheirismo entre todos&#8221;,\u00a0<\/strong>completou o arqueiro.<br \/>\nSobre a principal contrata\u00e7\u00e3o do Jacare\u00ed Futsal, o t\u00e9cnico Juliano Martins, ex-Gr\u00eamio Mogiano e mais conhecido como &#8220;Jab\u00e1&#8221;, Donha declarou o seguinte:\u00a0<strong>&#8220;J\u00e1 conhecia o Jab\u00e1 nas vezes que jogamos contra, por\u00e9m \u00e9 a primeira vez que trabalhamos juntos, e estou gostando bastante de como ele lida com os atletas e os treinamentos tamb\u00e9m. Apesar de estarmos focados nos f\u00edsicos com bola, ele j\u00e1 est\u00e1 colocando um padr\u00e3o de jogo&#8221;,\u00a0<\/strong>finalizou o goleiro jacareiense.<br \/>\nPela Liga Paulista de Futsal (LPF), principal torneio das quadras do estado de S\u00e3o Paulo, o clube de Jacare\u00ed-SP\u00a0est\u00e1 no grupo A e enfrentar\u00e1, na primeira fase, em turno \u00fanico, A.A. FIB, Corinthians, atual campe\u00e3o, S\u00e3o Jos\u00e9, S\u00e3o Caetano, Yoka, Pulo do Gato e os estreantes Pomp\u00e9ia e Atl\u00e9tico Guarulhense. A data da estreia est\u00e1 prevista a segunda semana de mar\u00e7o; o grupo B \u00e9 composto pelos seguintes times:\u00a0ADC Intelli\/Orl\u00e2ndia, Sorocaba,\u00a0Gr\u00eamio Mogiano, Taubat\u00e9, A.D. Indaiatuba, S\u00e3o Paulo, A.D. S\u00e3o Bernardo, A.A.B.B. e Dracena, que tamb\u00e9m estrear\u00e1 pelo torneio.<br \/>\n&nbsp;<br \/>\nPor Assessoria FPFS<br \/>\nCom informa\u00e7\u00f5es: Liga Paulista de Futsal (LPF)<br \/>\nFoto: Divulga\u00e7\u00e3o\/Arquivo pessoal de Bruno Donha<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Na \u00faltima semana, o Jacare\u00ed Futsal, time do interior paulista, iniciou oficialmente sua\u00a0pr\u00e9-temporada. Goleiro da equipe jacareiense, Bruno Donha<\/p>\n","protected":false},"author":1,"featured_media":9151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29,32],"tags":[271,429,873,940,1205,1334,1380,1382,1409,1937,2323,2482,2489],"class_list":["post-9150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interior","category-maiores","tag-arqueiro","tag-bruno","tag-donha","tag-entrevista","tag-goleiro","tag-interior","tag-jacarei","tag-jacareienses","tag-jogador","tag-pre-temporada","tag-sonoras","tag-traves","tag-treinamentos"],"_links":{"self":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts\/9150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/comments?post=9150"}],"version-history":[{"count":0,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/posts\/9150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/media?parent=9150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/categories?post=9150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.federacaopaulistadefutsal.com.br\/novo\/wp-json\/wp\/v2\/tags?post=9150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}